{"id":9412,"date":"2024-07-02T08:39:39","date_gmt":"2024-07-02T05:39:39","guid":{"rendered":"https:\/\/www.emn.ee\/publication\/illegal-employment-of-third-country-nationals-2017-2022-2\/"},"modified":"2025-12-18T17:15:12","modified_gmt":"2025-12-18T14:15:12","slug":"illegal-employment-of-third-country-nationals-2017-2022-2","status":"publish","type":"publication","link":"https:\/\/www.emn.ee\/en\/publication\/illegal-employment-of-third-country-nationals-2017-2022-2\/","title":{"rendered":"Illegal employment of third-country nationals: 2017-2022 situation analysis"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":6,"featured_media":9418,"template":"","meta":{"_acf_changed":false,"footnotes":""},"tags":[],"publication-catalog":[690],"class_list":["post-9412","publication","type-publication","status-publish","has-post-thumbnail","hentry","publication-catalog-studies-2"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Illegal employment of third-country nationals: 2017-2022 situation analysis - EMN<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emn.ee\/en\/publication\/illegal-employment-of-third-country-nationals-2017-2022-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Illegal employment of third-country nationals: 2017-2022 situation analysis - EMN\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emn.ee\/en\/publication\/illegal-employment-of-third-country-nationals-2017-2022-2\/\" \/>\n<meta property=\"og:site_name\" content=\"EMN\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-18T14:15:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.emn.ee\/wp-content\/uploads\/2025\/09\/llegal-emp.png\" \/>\n\t<meta property=\"og:image:width\" content=\"758\" \/>\n\t<meta property=\"og:image:height\" content=\"1071\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.emn.ee\/en\/publication\/illegal-employment-of-third-country-nationals-2017-2022-2\/\",\"url\":\"https:\/\/www.emn.ee\/en\/publication\/illegal-employment-of-third-country-nationals-2017-2022-2\/\",\"name\":\"Illegal employment of third-country nationals: 2017-2022 situation analysis - EMN\",\"isPartOf\":{\"@id\":\"https:\/\/www.emn.ee\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.emn.ee\/en\/publication\/illegal-employment-of-third-country-nationals-2017-2022-2\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.emn.ee\/en\/publication\/illegal-employment-of-third-country-nationals-2017-2022-2\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.emn.ee\/wp-content\/uploads\/2025\/09\/llegal-emp.png\",\"datePublished\":\"2024-07-02T05:39:39+00:00\",\"dateModified\":\"2025-12-18T14:15:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.emn.ee\/en\/publication\/illegal-employment-of-third-country-nationals-2017-2022-2\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.emn.ee\/en\/publication\/illegal-employment-of-third-country-nationals-2017-2022-2\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.emn.ee\/en\/publication\/illegal-employment-of-third-country-nationals-2017-2022-2\/#primaryimage\",\"url\":\"https:\/\/www.emn.ee\/wp-content\/uploads\/2025\/09\/llegal-emp.png\",\"contentUrl\":\"https:\/\/www.emn.ee\/wp-content\/uploads\/2025\/09\/llegal-emp.png\",\"width\":758,\"height\":1071},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.emn.ee\/en\/publication\/illegal-employment-of-third-country-nationals-2017-2022-2\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.emn.ee\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Illegal employment of third-country nationals: 2017-2022 situation analysis\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.emn.ee\/en\/#website\",\"url\":\"https:\/\/www.emn.ee\/en\/\",\"name\":\"EMN\",\"description\":\"Euroopa R&auml;ndev&otilde;rgustiku (EMN) Eesti kontaktpunkt\",\"publisher\":{\"@id\":\"https:\/\/www.emn.ee\/en\/#organization\"},\"alternateName\":\"European Migration Network\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.emn.ee\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.emn.ee\/en\/#organization\",\"name\":\"EMN\",\"url\":\"https:\/\/www.emn.ee\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.emn.ee\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.emn.ee\/wp-content\/uploads\/2025\/09\/emn-logo-big.svg\",\"contentUrl\":\"https:\/\/www.emn.ee\/wp-content\/uploads\/2025\/09\/emn-logo-big.svg\",\"caption\":\"EMN\"},\"image\":{\"@id\":\"https:\/\/www.emn.ee\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Illegal employment of third-country nationals: 2017-2022 situation analysis - EMN","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emn.ee\/en\/publication\/illegal-employment-of-third-country-nationals-2017-2022-2\/","og_locale":"en_US","og_type":"article","og_title":"Illegal employment of third-country nationals: 2017-2022 situation analysis - EMN","og_url":"https:\/\/www.emn.ee\/en\/publication\/illegal-employment-of-third-country-nationals-2017-2022-2\/","og_site_name":"EMN","article_modified_time":"2025-12-18T14:15:12+00:00","og_image":[{"width":758,"height":1071,"url":"https:\/\/www.emn.ee\/wp-content\/uploads\/2025\/09\/llegal-emp.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.emn.ee\/en\/publication\/illegal-employment-of-third-country-nationals-2017-2022-2\/","url":"https:\/\/www.emn.ee\/en\/publication\/illegal-employment-of-third-country-nationals-2017-2022-2\/","name":"Illegal employment of third-country nationals: 2017-2022 situation analysis - EMN","isPartOf":{"@id":"https:\/\/www.emn.ee\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.emn.ee\/en\/publication\/illegal-employment-of-third-country-nationals-2017-2022-2\/#primaryimage"},"image":{"@id":"https:\/\/www.emn.ee\/en\/publication\/illegal-employment-of-third-country-nationals-2017-2022-2\/#primaryimage"},"thumbnailUrl":"https:\/\/www.emn.ee\/wp-content\/uploads\/2025\/09\/llegal-emp.png","datePublished":"2024-07-02T05:39:39+00:00","dateModified":"2025-12-18T14:15:12+00:00","breadcrumb":{"@id":"https:\/\/www.emn.ee\/en\/publication\/illegal-employment-of-third-country-nationals-2017-2022-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emn.ee\/en\/publication\/illegal-employment-of-third-country-nationals-2017-2022-2\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.emn.ee\/en\/publication\/illegal-employment-of-third-country-nationals-2017-2022-2\/#primaryimage","url":"https:\/\/www.emn.ee\/wp-content\/uploads\/2025\/09\/llegal-emp.png","contentUrl":"https:\/\/www.emn.ee\/wp-content\/uploads\/2025\/09\/llegal-emp.png","width":758,"height":1071},{"@type":"BreadcrumbList","@id":"https:\/\/www.emn.ee\/en\/publication\/illegal-employment-of-third-country-nationals-2017-2022-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.emn.ee\/en\/"},{"@type":"ListItem","position":2,"name":"Illegal employment of third-country nationals: 2017-2022 situation analysis"}]},{"@type":"WebSite","@id":"https:\/\/www.emn.ee\/en\/#website","url":"https:\/\/www.emn.ee\/en\/","name":"EMN","description":"Euroopa R&auml;ndev&otilde;rgustiku (EMN) Eesti kontaktpunkt","publisher":{"@id":"https:\/\/www.emn.ee\/en\/#organization"},"alternateName":"European Migration Network","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emn.ee\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.emn.ee\/en\/#organization","name":"EMN","url":"https:\/\/www.emn.ee\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.emn.ee\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.emn.ee\/wp-content\/uploads\/2025\/09\/emn-logo-big.svg","contentUrl":"https:\/\/www.emn.ee\/wp-content\/uploads\/2025\/09\/emn-logo-big.svg","caption":"EMN"},"image":{"@id":"https:\/\/www.emn.ee\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/www.emn.ee\/en\/wp-json\/wp\/v2\/publication\/9412","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.emn.ee\/en\/wp-json\/wp\/v2\/publication"}],"about":[{"href":"https:\/\/www.emn.ee\/en\/wp-json\/wp\/v2\/types\/publication"}],"author":[{"embeddable":true,"href":"https:\/\/www.emn.ee\/en\/wp-json\/wp\/v2\/users\/6"}],"version-history":[{"count":2,"href":"https:\/\/www.emn.ee\/en\/wp-json\/wp\/v2\/publication\/9412\/revisions"}],"predecessor-version":[{"id":12379,"href":"https:\/\/www.emn.ee\/en\/wp-json\/wp\/v2\/publication\/9412\/revisions\/12379"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.emn.ee\/en\/wp-json\/wp\/v2\/media\/9418"}],"wp:attachment":[{"href":"https:\/\/www.emn.ee\/en\/wp-json\/wp\/v2\/media?parent=9412"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emn.ee\/en\/wp-json\/wp\/v2\/tags?post=9412"},{"taxonomy":"publication-catalog","embeddable":true,"href":"https:\/\/www.emn.ee\/en\/wp-json\/wp\/v2\/publication-catalog?post=9412"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}